{"id":6380,"date":"2020-10-13T12:28:31","date_gmt":"2020-10-13T12:28:31","guid":{"rendered":"https:\/\/emporiozani.com\/shop\/uncategorized\/piatto-piano-conf-2-pz-taormina\/"},"modified":"2020-10-13T12:28:31","modified_gmt":"2020-10-13T12:28:31","slug":"piatto-piano-conf-2-pz-taormina","status":"publish","type":"product","link":"https:\/\/touchmel.it\/en\/shop\/at-the-table\/touch-mel-melamine-plates-and-tableware\/taormina-en\/piatto-piano-conf-2-pz-taormina\/","title":{"rendered":"Piatto Piano conf. 2 pz &#8211; Taormina"},"content":{"rendered":"<p>Taormina riprende e innova il tema classico di Touch-MeL, che continua il suo viaggio nell\u2019Europa Mediterranea per approdare nella nostra amata Sicilia, l\u00e0 dove tutto \u00e8 magia. La nuova linea propone un decoro classico, rivisitato per celebrare i colori ed il gusto di una terra meravigliosa, bagnata dal mare e sospesa nel tempo con le sue tradizioni secolari, che vedono gli artigiani locali creare con le proprie mani oggetti incantevoli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Taormina riprende e innova il tema classico di Touch-MeL, che continua il suo viaggio nell\u2019Europa Mediterranea per approdare nella nostra<\/p>\n","protected":false},"featured_media":6381,"template":"","meta":[],"product_cat":[1836,1837,1863],"product_tag":[1882],"class_list":["post-6380","product","type-product","status-publish","has-post-thumbnail","product_cat-at-the-table","product_cat-touch-mel-melamine-plates-and-tableware","product_cat-taormina-en","product_tag-taormina-en","first","outofstock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/product\/6380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/media\/6381"}],"wp:attachment":[{"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/media?parent=6380"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/product_cat?post=6380"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/product_tag?post=6380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}