{"id":6340,"date":"2020-10-13T12:30:11","date_gmt":"2020-10-13T12:30:11","guid":{"rendered":"https:\/\/emporiozani.com\/shop\/uncategorized\/piatto-fondo-conf-2-pz-havana-blu\/"},"modified":"2020-10-13T12:30:11","modified_gmt":"2020-10-13T12:30:11","slug":"piatto-fondo-conf-2-pz-havana-blu","status":"publish","type":"product","link":"https:\/\/touchmel.it\/en\/shop\/at-the-table\/touch-mel-melamine-plates-and-tableware\/havana-blu-en\/piatto-fondo-conf-2-pz-havana-blu\/","title":{"rendered":"Piatto Fondo conf. 2 pz &#8211; Havana blu"},"content":{"rendered":"<p>Havana Blu ha tutto il gusto a ritmo di salsa delle notti cubane. Il viaggio di Touch-MeL arriva fino ai Caraibi e assume nuove tonalit\u00e0 di blu, con un decoro che ha tutto il profumo e il fascino misterioso di quel bellissimo fiore di Mandevilla. Un gioiello cresciuto libero a Cienfuegos e sempre verde, questa dipladenia blu, i cui fiori profumati resistono bene anche alle afose estati in citt\u00e0 e sono pronti ad allietare le nostre case anche con l\u2019arrivo dei primi freddi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Havana Blu ha tutto il gusto a ritmo di salsa delle notti cubane. Il viaggio di Touch-MeL arriva fino ai<\/p>\n","protected":false},"featured_media":6341,"template":"","meta":[],"product_cat":[1836,1837,1848],"product_tag":[1879],"class_list":["post-6340","product","type-product","status-publish","has-post-thumbnail","product_cat-at-the-table","product_cat-touch-mel-melamine-plates-and-tableware","product_cat-havana-blu-en","product_tag-havana-blu-en","first","outofstock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/product\/6340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/media\/6341"}],"wp:attachment":[{"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/media?parent=6340"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/product_cat?post=6340"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/touchmel.it\/en\/wp-json\/wp\/v2\/product_tag?post=6340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}